{"id":1458,"date":"2023-05-15T08:27:32","date_gmt":"2023-05-15T08:27:32","guid":{"rendered":"https:\/\/skyhaus.modeltheme.com\/?page_id=1458"},"modified":"2024-09-22T23:09:13","modified_gmt":"2024-09-22T23:09:13","slug":"home","status":"publish","type":"page","link":"https:\/\/drivendivinevilla.com\/","title":{"rendered":"Home"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"1458\" class=\"elementor elementor-1458\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-79649a1 elementor-section-stretched elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"79649a1\" data-element_type=\"section\" data-settings=\"{&quot;stretch_section&quot;:&quot;section-stretched&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-f2449fd\" data-id=\"f2449fd\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-efb5eac elementor-widget elementor-widget-mt_addon_slider\" data-id=\"efb5eac\" data-element_type=\"widget\" data-widget_type=\"mt_addon_slider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"mt-slider swiper-container custom  \" dir=\"ltr\" data-settings=\"{&quot;autoplay&quot;:true,&quot;autoplaySpeed&quot;:5000,&quot;speed&quot;:1000,&quot;direction&quot;:&quot;horizontal&quot;,&quot;effect&quot;:&quot;fade&quot;,&quot;initialSlide&quot;:0,&quot;grabCursor&quot;:false,&quot;loop&quot;:true,&quot;pauseOnHover&quot;:true,&quot;parallax&quot;:false,&quot;mousewheel&quot;:false,&quot;navigation&quot;:&quot;&quot;,&quot;pagination&quot;:&quot;yes&quot;,&quot;pagiStyle&quot;:&quot;style-3&quot;}\">\r\n\t\t\t<div class=\"swiper-wrapper\">\r\n\t\t\t\t\t\t\t\t<div class=\"swiper-slide elementor-repeater-item-cfef5ec\">\r\n\t\t\t\t\t<div class=\"slide-img-wrap\"><img decoding=\"async\" src=\"https:\/\/drivendivinevilla.com\/wp-content\/uploads\/2024\/02\/IMG_1162-scaled.jpg\" alt=\"Home\" class=\"slide-img kenburns kenburns-top\" style=\"animation-duration: 12000ms;\"\/><\/div>\t\t\t\t\t<div class=\"slider-content-wrap text-left\">\r\n\t\t\t\t\t\t<div class=\"content-width\">\r\n                            <div class=\"border-layers\"><span><\/span><span><\/span><span><\/span><span><\/span><\/div>\t\t\t\t\t\t\t<div class=\"slider-content\">\r\n\t\t\t\t\t\t\t\t        <div class=\"mt-caption heading\">\r\n        <div class=\"inner-layer\"><div class=\"mt-cap char-expand\" data-splitting>Welcome  to<\/br>Driven &amp; Divine <br><\/div><\/div>        <\/div>\r\n                <div class=\"mt-caption desc\">\r\n        <div class=\"inner-layer\"><div class=\"mt-cap\" data-animation=\"mt-fadeInUp\" data-delay=\"1400ms\" data-duration=\"1000ms\"> <\/br> <span> VILLA <\/span><\/div><\/div>        <\/div>\r\n        \t\t\t\t\t\t\t\t<div class=\"mt-btn-group text-masking\">\r\n\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/drivendivinevilla.com\/index.php\/booking-form\/\" class=\"slider-btn\" data-animation=\"mt-fadeIn\" data-delay=\"1000ms\" data-duration=\"1000ms\">Send a inquiry <i class=\"fas fa-angle-right\"><\/i><\/a>\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t<\/div>\r\n\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t<div class=\"swiper-slide elementor-repeater-item-d108f35\">\r\n\t\t\t\t\t<div class=\"slide-img-wrap\"><img decoding=\"async\" src=\"https:\/\/drivendivinevilla.com\/wp-content\/uploads\/2024\/02\/DJI_0418-1-scaled.jpg\" alt=\"Home\" class=\"slide-img kenburns kenburns-left\" style=\"animation-duration: 12000ms;\"\/><\/div><div data-animation=\"mt-fadeInLeft\" data-delay=\"1000ms\" data-duration=\"1000ms\" class=\"slider-layer left\"><\/div>\t\t\t\t\t<div class=\"slider-content-wrap text-left\">\r\n\t\t\t\t\t\t<div class=\"content-width\">\r\n                            \t\t\t\t\t\t\t<div class=\"slider-content\">\r\n\t\t\t\t\t\t\t\t        <div class=\"mt-caption heading\">\r\n        <div class=\"inner-layer\"><div class=\"mt-cap char-expand\" data-splitting>Host your <\/br> Next Event !<\/br>\n<\/div><\/div>        <\/div>\r\n        \t\t\t\t\t\t\t\t<div class=\"mt-btn-group text-masking\">\r\n\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/drivendivinevilla.com\/index.php\/booking-form\/\" class=\"slider-btn\" data-animation=\"mt-fadeIn\" data-delay=\"1000ms\" data-duration=\"1000ms\">Send an inquiry <i class=\"fas fa-chevron-right\"><\/i><\/a>\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t<\/div>\r\n\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t<\/div>\r\n\t\t\t        <div class=\"mt-slider-controls style- autoplay-active\">\r\n        <div class=\"mt-swiper-pagination pagi-style-3\"><\/div>        <\/div>\r\n        \t\t\t<div class=\"slider-preloader\"><div class=\"dot-flashing\"><\/div><\/div>\r\n\t\t<\/div>\r\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-b8b513c elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"b8b513c\" data-element_type=\"section\" id=\"about\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-ceff1a7 elementor-invisible\" data-id=\"ceff1a7\" data-element_type=\"column\" data-settings=\"{&quot;animation&quot;:&quot;fadeInLeft&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-f10398e elementor-widget elementor-widget-title-subtitle\" data-id=\"f10398e\" data-element_type=\"widget\" data-widget_type=\"title-subtitle.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t    <div  class=\"mt-addons-title-subtile \">\r\n      \r\n      \r\n      \r\n                           \r\n      <h2 class=\"mt-addons-title-section left\" style=\"color:;font-weight:;font-size:px;\">DRIVEN &amp; DIVINE  ENTERPRISE  <span class=\"mt-underline-text curved\" style=\"color:;\"><\/span> <\/h2>\r\n\r\n                    \r\n          <\/div>\r\n\r\n    \t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6907806 elementor-widget elementor-widget-mt-spacer\" data-id=\"6907806\" data-element_type=\"widget\" data-widget_type=\"mt-spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t    <div class=\"mt-addons-flexible-spacer \">\r\n      <div class=\"mt-addons-empty-spacer-desktop\" style=\"height: 20px;\"><\/div>\r\n      <div class=\"mt-addons-empty-spacer-mobile\" style=\"height: px;\"><\/div>\r\n      <div class=\"mt-addons-empty-spacer-tablet\" style=\"height: 20px;\"><\/div>\r\n    <\/div>\r\n   \r\n    \t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-07f6d52 elementor-widget elementor-widget-text-editor\" data-id=\"07f6d52\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><em>Experience the versatility of our villa, where the possibilities for events are endless! Whether you&#8217;re planning a corporate gathering, a cozy baby reveal, or a celebratory graduation party, our space caters to every occasion. With customizable settings and ample space, Driven &amp; Divine Enterprise is your ultimate destination for creating unforgettable memories, no matter the celebration!<\/em><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ffef697 elementor-widget elementor-widget-mt-spacer\" data-id=\"ffef697\" data-element_type=\"widget\" data-widget_type=\"mt-spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t    <div class=\"mt-addons-flexible-spacer \">\r\n      <div class=\"mt-addons-empty-spacer-desktop\" style=\"height: 20px;\"><\/div>\r\n      <div class=\"mt-addons-empty-spacer-mobile\" style=\"height: 20px;\"><\/div>\r\n      <div class=\"mt-addons-empty-spacer-tablet\" style=\"height: 20px;\"><\/div>\r\n    <\/div>\r\n   \r\n    \t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f42e344 elementor-widget elementor-widget-mt-spacer\" data-id=\"f42e344\" data-element_type=\"widget\" data-widget_type=\"mt-spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t    <div class=\"mt-addons-flexible-spacer \">\r\n      <div class=\"mt-addons-empty-spacer-desktop\" style=\"height: 20px;\"><\/div>\r\n      <div class=\"mt-addons-empty-spacer-mobile\" style=\"height: px;\"><\/div>\r\n      <div class=\"mt-addons-empty-spacer-tablet\" style=\"height: 20px;\"><\/div>\r\n    <\/div>\r\n   \r\n    \t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-8f1072b elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"8f1072b\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-915f1b3\" data-id=\"915f1b3\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-b367e02 elementor-widget elementor-widget-icon-with-text\" data-id=\"b367e02\" data-element_type=\"widget\" data-widget_type=\"icon-with-text.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t  <div style=\";;\" class=\"mt-icon-listgroup-item wow   text-left \">\r\n      <div class=\"mt-icon-listgroup-holder mt-addons-before_content\" >\r\n\r\n        <div class=\"mt-icon-listgroup-icon-holder-inner \" style=\"margin-right:15px;\">\r\n                    <a href=\"https:\/\/skyhaus.modeltheme.com\/#gallery\" target=\"_blank\" rel=\"\">\r\n            <img decoding=\"async\" alt=\"list-image\" style=\"max-width:50px;margin-right: px;\" class=\"mt-image-list\" src=\"https:\/\/drivendivinevilla.com\/wp-content\/uploads\/2024\/02\/IMG_0475-removebg-preview.png\">\r\n          <\/a>\r\n                  <\/div>\r\n        <div class=\"mt-icon-listgroup-content-holder-inner\" >\r\n          <p class=\"mt-icon-listgroup-title\"><a href=\"https:\/\/skyhaus.modeltheme.com\/#gallery\" target=\"_blank\" rel=\"\" style=\"color:#777777;\">Beds<\/a>\r\n          <\/p>\r\n                      <h6 class=\"mt-icon-listgroup-text\" style=\"\"> 5 <\/h6>      \r\n                   <\/div>\r\n      <\/div>\r\n   <\/div>\r\n     \t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-a9a6fd8\" data-id=\"a9a6fd8\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-443294b elementor-widget elementor-widget-icon-with-text\" data-id=\"443294b\" data-element_type=\"widget\" data-widget_type=\"icon-with-text.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t  <div style=\";;\" class=\"mt-icon-listgroup-item wow   text-left \">\r\n      <div class=\"mt-icon-listgroup-holder mt-addons-before_content\" >\r\n\r\n        <div class=\"mt-icon-listgroup-icon-holder-inner \" style=\"margin-right:15px;\">\r\n                    <a href=\"https:\/\/skyhaus.modeltheme.com\/#gallery\" target=\"_blank\" rel=\"\">\r\n            <img decoding=\"async\" alt=\"list-image\" style=\"max-width:50px;margin-right: px;\" class=\"mt-image-list\" src=\"https:\/\/drivendivinevilla.com\/wp-content\/uploads\/2024\/02\/IMG_0481.png\">\r\n          <\/a>\r\n                  <\/div>\r\n        <div class=\"mt-icon-listgroup-content-holder-inner\" >\r\n          <p class=\"mt-icon-listgroup-title\"><a href=\"https:\/\/skyhaus.modeltheme.com\/#gallery\" target=\"_blank\" rel=\"\" style=\"color:#777777;\">Baths<\/a>\r\n          <\/p>\r\n                      <h6 class=\"mt-icon-listgroup-text\" style=\"\"> 6 <\/h6>      \r\n                   <\/div>\r\n      <\/div>\r\n   <\/div>\r\n     \t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-376390e elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"376390e\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-bac3449\" data-id=\"bac3449\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-149351d elementor-widget elementor-widget-icon-with-text\" data-id=\"149351d\" data-element_type=\"widget\" data-widget_type=\"icon-with-text.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t  <div style=\";;\" class=\"mt-icon-listgroup-item wow   text-left \">\r\n      <div class=\"mt-icon-listgroup-holder mt-addons-before_content\" >\r\n\r\n        <div class=\"mt-icon-listgroup-icon-holder-inner \" style=\"margin-right:15px;\">\r\n                    <a href=\"https:\/\/skyhaus.modeltheme.com\/#gallery\" target=\"_blank\" rel=\"\">\r\n            <img decoding=\"async\" alt=\"list-image\" style=\"max-width:50px;margin-right: px;\" class=\"mt-image-list\" src=\"https:\/\/drivendivinevilla.com\/wp-content\/uploads\/2024\/02\/IMG_0479.png\">\r\n          <\/a>\r\n                  <\/div>\r\n        <div class=\"mt-icon-listgroup-content-holder-inner\" >\r\n          <p class=\"mt-icon-listgroup-title\"><a href=\"https:\/\/skyhaus.modeltheme.com\/#gallery\" target=\"_blank\" rel=\"\" style=\"color:#777777;\">Garages<\/a>\r\n          <\/p>\r\n                      <h6 class=\"mt-icon-listgroup-text\" style=\"\"> 2 <\/h6>      \r\n                   <\/div>\r\n      <\/div>\r\n   <\/div>\r\n     \t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-1d3c7a9\" data-id=\"1d3c7a9\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-27512c5 elementor-widget elementor-widget-icon-with-text\" data-id=\"27512c5\" data-element_type=\"widget\" data-widget_type=\"icon-with-text.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t  <div style=\";;\" class=\"mt-icon-listgroup-item wow   text-left \">\r\n      <div class=\"mt-icon-listgroup-holder mt-addons-before_content\" >\r\n\r\n        <div class=\"mt-icon-listgroup-icon-holder-inner \" style=\"margin-right:15px;\">\r\n                    <a href=\"https:\/\/skyhaus.modeltheme.com\/#gallery\" target=\"_blank\" rel=\"\">\r\n            <img decoding=\"async\" alt=\"list-image\" style=\"max-width:50px;margin-right: px;\" class=\"mt-image-list\" src=\"https:\/\/drivendivinevilla.com\/wp-content\/uploads\/2024\/02\/IMG_0480.png\">\r\n          <\/a>\r\n                  <\/div>\r\n        <div class=\"mt-icon-listgroup-content-holder-inner\" >\r\n          <p class=\"mt-icon-listgroup-title\"><a href=\"https:\/\/skyhaus.modeltheme.com\/#gallery\" target=\"_blank\" rel=\"\" style=\"color:#777777;\">Kitchens<\/a>\r\n          <\/p>\r\n                      <h6 class=\"mt-icon-listgroup-text\" style=\"\"> 2 <\/h6>      \r\n                   <\/div>\r\n      <\/div>\r\n   <\/div>\r\n     \t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-37f6c4f elementor-invisible\" data-id=\"37f6c4f\" data-element_type=\"column\" data-settings=\"{&quot;animation&quot;:&quot;fadeInRight&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-46ec587 zoom-img--main elementor-widget elementor-widget-image\" data-id=\"46ec587\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"http:\/\/drivendivinevilla.com\/wp-content\/uploads\/2024\/02\/IMG_1159-1-scaled.jpg\" data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-title=\"IMG_1159\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MjQyNywidXJsIjoiaHR0cHM6XC9cL2RyaXZlbmRpdmluZXZpbGxhLmNvbVwvd3AtY29udGVudFwvdXBsb2Fkc1wvMjAyNFwvMDJcL0lNR18xMTU5LTEtc2NhbGVkLmpwZyJ9\">\n\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/drivendivinevilla.com\/wp-content\/uploads\/2024\/02\/IMG_1159-1-scaled.jpg\" title=\"IMG_1159\" alt=\"IMG_1159\" loading=\"lazy\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t<div class=\"elementor-element elementor-element-394a67c e-flex e-con-boxed e-con e-parent\" data-id=\"394a67c\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-063a1e5 elementor-widget elementor-widget-spacer\" data-id=\"063a1e5\" data-element_type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-b0d3c6c elementor-section-boxed elementor-section-height-default elementor-section-height-default elementor-invisible\" data-id=\"b0d3c6c\" data-element_type=\"section\" id=\"highlights\" data-settings=\"{&quot;animation&quot;:&quot;fadeInUp&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-b491f10\" data-id=\"b491f10\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-9e2e138 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"9e2e138\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-bf03205\" data-id=\"bf03205\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-61c874e elementor-widget elementor-widget-title-subtitle\" data-id=\"61c874e\" data-element_type=\"widget\" data-widget_type=\"title-subtitle.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t    <div  class=\"mt-addons-title-subtile \">\r\n      \r\n      \r\n      \r\n                           \r\n      <h2 class=\"mt-addons-title-section text-left\" style=\"color:#0A0A0A;font-weight:;font-size:px;\">Property Highlights <span class=\"mt-underline-text curved\" style=\"color:#0A0A0A;\"><\/span> <\/h2>\r\n\r\n                    \r\n          <\/div>\r\n\r\n    \t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-296a0f9\" data-id=\"296a0f9\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-5535952 elementor-widget elementor-widget-text-editor\" data-id=\"5535952\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Discover pure luxury at this magnificent villa with stunning views and spacious landscapes \u2013 ideal for grand events and beyond. Embrace a lifestyle where sophistication and opulence meet at every turn.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<div class=\"elementor-element elementor-element-b0074c8 elementor-widget elementor-widget-mt-spacer\" data-id=\"b0074c8\" data-element_type=\"widget\" data-widget_type=\"mt-spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t    <div class=\"mt-addons-flexible-spacer \">\r\n      <div class=\"mt-addons-empty-spacer-desktop\" style=\"height: 37px;\"><\/div>\r\n      <div class=\"mt-addons-empty-spacer-mobile\" style=\"height: 37px;\"><\/div>\r\n      <div class=\"mt-addons-empty-spacer-tablet\" style=\"height: 37px;\"><\/div>\r\n    <\/div>\r\n   \r\n    \t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-db3f89a skyhaus-highlights elementor-section-boxed elementor-section-height-default elementor-section-height-default elementor-invisible\" data-id=\"db3f89a\" data-element_type=\"section\" data-settings=\"{&quot;animation&quot;:&quot;fadeInUp&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-414b674\" data-id=\"414b674\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-e95bd9b elementor-widget elementor-widget-hero-slider\" data-id=\"e95bd9b\" data-element_type=\"widget\" data-widget_type=\"hero-slider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\r\n        <div class=\"mt-addons-swiper-container\">      <div class=\"mt-swipper-carusel-position\" style=\"position:relative;\">\r\n        <div id=\"mt-addons-swipper-6a045ad82395e\" \r\n                  data-swiper-id=\"mt-addons-swipper-6a045ad82395e\"  \r\n        data-swiper-autoplay=\"no\"\r\n        data-swiper-delay=\"600\" \r\n        data-swiper-desktop-items=\"3\" \r\n        data-swiper-mobile-items=\"1\" \r\n        data-swiper-tablet-items=\"3\" \r\n        data-swiper-space-between-items=\"30\" \r\n        data-swiper-allow-touch-move=\"yes\" \r\n        data-swiper-effect=\"\"\r\n        data-swiper-grab-cursor =\"\"\r\n        data-swiper-infinite-loop =\"yes\"\r\n        data-swiper-centered-slides =\"\"\r\n        data-swiper-navigation =\"yes\"\r\n        data-swiper-pagination =\"no\"\r\n\r\n\r\n     \r\n          class=\"mt-addons-hero-slider mt-addons-swipper swiper\">\r\n\r\n                        <div class=\"swiper-wrapper\">                                                              \r\n                    <div class=\"swiper-slide elementor-repeater-item-3812588\">\r\n                                        <div style=\"background-image: url(https:\/\/drivendivinevilla.com\/wp-content\/uploads\/2024\/02\/IMG_1164-scaled.jpg); ;height:500px;\" class=\"mt-addons-hero-slider-background\">\r\n                      <div class=\"mt-addons-hero-slider-bg\" style=\" background-color: \">\r\n                        <div class=\"container\">\r\n                          <div class=\"mt-addons-hero-slider-holder text-center\">\r\n                                                                                        <h2 class=\"mt-addons-hero-slider-title\" style=\";font-size:20px;line-height:30px;font-weight:600;\"> Amazing Views <\/h2>\r\n                                                                                                                    <p class=\"mt-addons-hero-slider-subtitle\" style=\";font-size:px;line-height:px;font-weight:;\">   A majestic retreat with unparalleled views and luxurious living. <\/p>\r\n                                                                                                                                                                        <\/div>\r\n                        <\/div>\r\n                      <\/div>\r\n                    <\/div>\r\n                  <\/div>\r\n                                  \r\n                    <div class=\"swiper-slide elementor-repeater-item-33ad575\">\r\n                                        <div style=\"background-image: url(https:\/\/drivendivinevilla.com\/wp-content\/uploads\/2024\/02\/IMG_1209-scaled.jpg); ;height:500px;\" class=\"mt-addons-hero-slider-background\">\r\n                      <div class=\"mt-addons-hero-slider-bg\" style=\" background-color: \">\r\n                        <div class=\"container\">\r\n                          <div class=\"mt-addons-hero-slider-holder text-center\">\r\n                                                                                        <h2 class=\"mt-addons-hero-slider-title\" style=\";font-size:20px;line-height:30px;font-weight:600;\"> Spectacular Neighborhood <\/h2>\r\n                                                                                                                    <p class=\"mt-addons-hero-slider-subtitle\" style=\";font-size:px;line-height:px;font-weight:;\">  Discover an incredible getaway in a safe and amazing neighborhood. <\/p>\r\n                                                                                                                                                                        <\/div>\r\n                        <\/div>\r\n                      <\/div>\r\n                    <\/div>\r\n                  <\/div>\r\n                                  \r\n                    <div class=\"swiper-slide elementor-repeater-item-9720fd8\">\r\n                                        <div style=\"background-image: url(https:\/\/drivendivinevilla.com\/wp-content\/uploads\/2024\/02\/IMG_1211-scaled.jpg); ;height:500px;\" class=\"mt-addons-hero-slider-background\">\r\n                      <div class=\"mt-addons-hero-slider-bg\" style=\" background-color: \">\r\n                        <div class=\"container\">\r\n                          <div class=\"mt-addons-hero-slider-holder text-center\">\r\n                                                                                        <h2 class=\"mt-addons-hero-slider-title\" style=\";font-size:20px;line-height:30px;font-weight:600;\">  Innovative designs  <\/h2>\r\n                                                                                                                    <p class=\"mt-addons-hero-slider-subtitle\" style=\";font-size:px;line-height:px;font-weight:;\">   Explore distinctive home designs crafted by a talented designer, blending unique tile styles with amazing concepts. <\/p>\r\n                                                                                                                                                                        <\/div>\r\n                        <\/div>\r\n                      <\/div>\r\n                    <\/div>\r\n                  <\/div>\r\n                                  \r\n                    <div class=\"swiper-slide elementor-repeater-item-f8956e3\">\r\n                                        <div style=\"background-image: url(https:\/\/drivendivinevilla.com\/wp-content\/uploads\/2024\/02\/IMG_1213-scaled.jpg); ;height:500px;\" class=\"mt-addons-hero-slider-background\">\r\n                      <div class=\"mt-addons-hero-slider-bg\" style=\" background-color: \">\r\n                        <div class=\"container\">\r\n                          <div class=\"mt-addons-hero-slider-holder text-center\">\r\n                                                                                        <h2 class=\"mt-addons-hero-slider-title\" style=\";font-size:20px;line-height:30px;font-weight:600;\"> Central and Convenient <\/h2>\r\n                                                                                                                    <p class=\"mt-addons-hero-slider-subtitle\" style=\";font-size:px;line-height:px;font-weight:;\">  This prime villa offers unparalleled convenience, situated near everything you need for a perfect lifestyle. <\/p>\r\n                                                                                                                                                                        <\/div>\r\n                        <\/div>\r\n                      <\/div>\r\n                    <\/div>\r\n                  <\/div>\r\n                                                      <\/div>                        \r\n        <i class=\"fas fa-arrow-left swiper-button-prev nav-square nav_middle_slider\" style=\"color:;background:\"><\/i>\r\n        <i class=\"fas fa-arrow-right swiper-button-next nav-square nav_middle_slider\" style=\"color:;background:\"><\/i>        <\/div>\r\n      <\/div>\r\n        <\/div>        \t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-8e9a0d3 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"8e9a0d3\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-8b2f2a9\" data-id=\"8b2f2a9\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-ce78253 elementor-widget elementor-widget-mt-spacer\" data-id=\"ce78253\" data-element_type=\"widget\" data-widget_type=\"mt-spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t    <div class=\"mt-addons-flexible-spacer \">\r\n      <div class=\"mt-addons-empty-spacer-desktop\" style=\"height: 80px;\"><\/div>\r\n      <div class=\"mt-addons-empty-spacer-mobile\" style=\"height: 50px;\"><\/div>\r\n      <div class=\"mt-addons-empty-spacer-tablet\" style=\"height: 80px;\"><\/div>\r\n    <\/div>\r\n   \r\n    \t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-a16653f elementor-section-stretched elementor-section-boxed elementor-section-height-default elementor-section-height-default elementor-invisible\" data-id=\"a16653f\" data-element_type=\"section\" id=\"amenities\" data-settings=\"{&quot;stretch_section&quot;:&quot;section-stretched&quot;,&quot;background_background&quot;:&quot;classic&quot;,&quot;animation&quot;:&quot;fadeInUp&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-1a35d9d tablet-view\" data-id=\"1a35d9d\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-4653d5c elementor-widget elementor-widget-mt-spacer\" data-id=\"4653d5c\" data-element_type=\"widget\" data-widget_type=\"mt-spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t    <div class=\"mt-addons-flexible-spacer \">\r\n      <div class=\"mt-addons-empty-spacer-desktop\" style=\"height: 90px;\"><\/div>\r\n      <div class=\"mt-addons-empty-spacer-mobile\" style=\"height: 50px;\"><\/div>\r\n      <div class=\"mt-addons-empty-spacer-tablet\" style=\"height: 70px;\"><\/div>\r\n    <\/div>\r\n   \r\n    \t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2dddaf3 elementor-widget elementor-widget-title-subtitle\" data-id=\"2dddaf3\" data-element_type=\"widget\" data-widget_type=\"title-subtitle.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t    <div  class=\"mt-addons-title-subtile \">\r\n      \r\n      \r\n      \r\n                           \r\n      <h2 class=\"mt-addons-title-section text-left\" style=\"color:#FFFFFF;font-weight:;font-size:px;\">Driven &amp; Divine Amenities <span class=\"mt-underline-text curved\" style=\"color:#FFFFFF;\"><\/span> <\/h2>\r\n\r\n                    \r\n          <\/div>\r\n\r\n    \t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-97ac810 elementor-widget elementor-widget-mt-tabs\" data-id=\"97ac810\" data-element_type=\"widget\" data-widget_type=\"mt-tabs.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t    <div class=\"mt-addons-tabs\">\r\n      <nav>\r\n        <ul class=\"mt-addons-tabs-nav  col-md-6\" style=\"background:#0A0A0A\"> \r\n                                  \r\n              <li><a href=\"#section-iconbox-1\"> \r\n                                <h5 class=\"mt-addons-tabs-nav-title\" style=\"color:#FFFFFF;\">Exterior Details<\/h5>\r\n              <\/a><\/li> \r\n                            \r\n              <li><a href=\"#section-iconbox-2\"> \r\n                                <h5 class=\"mt-addons-tabs-nav-title\" style=\"color:#FFFFFF;\">Interior Details<\/h5>\r\n              <\/a><\/li> \r\n                            \r\n              <li><a href=\"#section-iconbox-3\"> \r\n                                <h5 class=\"mt-addons-tabs-nav-title\" style=\"color:#FFFFFF;\">Room Dimensions<\/h5>\r\n              <\/a><\/li> \r\n                                  <\/ul>\r\n      <\/nav>\r\n      <div class=\"mt-addons-tab-content\">\r\n                                      <section id=\"section-iconbox-1\">\r\n              <div class=\"row\">\r\n                <div class=\"mt-addons-tab-flex-zone\">\r\n                  <div class=\"col-md-4 col-sm-12 text-left\">\r\n                      <p class=\"mt-addons-tab-content-title\">An inviting exterior welcomes with a spacious front yard, dazzling infinity pool, stylish bar lounge, enchanting botanical haven, a generously sized backyard, and a versatile event hall.<\/p>\r\n                      <p class=\"mt-addons-tab-content\"><ul class=\"skyhaus-zone-flex\" style=\"padding-left: 0rem; padding-top: 40px;\"><li>\u00a0<\/li><li style=\"list-style: none;\">Enchanting Botanical Haven<br \/><p class=\"skyhaus-description\" style=\"margin-top: 3px; color: #fff;\"><span style=\"color: #333333;\">Infinity Pool<\/span><\/p><\/li><li style=\"list-style: none;\"><p class=\"skyhaus-description\" style=\"margin-top: 3px; color: #fff;\">\u00a0<\/p><\/li><\/ul><ul class=\"skyhaus-zone-flex-2\" style=\"padding-left: 0rem;\"><li style=\"list-style: none;\"><p class=\"skyhaus-description\" style=\"margin-top: 3px; color: #fff;\">\u00a0<\/p><\/li><\/ul><\/p>\r\n                       \r\n\r\n\r\n                  <\/div>\r\n                    <div class=\"col-md-8 text-right\">\r\n                        <div class=\"zoom-img--main text-right\">\r\n                          <img decoding=\"async\" class=\"mt-addons-tab-content-image\" src=\"https:\/\/drivendivinevilla.com\/wp-content\/uploads\/2024\/02\/IMG_1183-scaled.jpg\" alt=\"tabs-image\">\r\n                        <\/div>\r\n                  <\/div>\r\n                <\/div>   \r\n              <\/div>   \r\n            <\/section>\r\n                                  <section id=\"section-iconbox-2\">\r\n              <div class=\"row\">\r\n                <div class=\"mt-addons-tab-flex-zone\">\r\n                  <div class=\"col-md-4 col-sm-12 text-left\">\r\n                      <p class=\"mt-addons-tab-content-title\">Discover dual-story elegance, a grand master bedroom suite, designer tile accents, luxurious custom furniture, and innovative, lavish bathrooms within the interiors of this exquisite property.<\/p>\r\n                      <p class=\"mt-addons-tab-content\"><p>\u00a0<\/p><p>Dual-Story Elegance<\/p><p><span style=\"color: #333333;\">Grand Bedroom Suites<\/span><\/p><ul class=\"skyhaus-zone-flex-2\" style=\"padding-left: 0rem;\"><li style=\"list-style: none;\"><p class=\"skyhaus-description\" style=\"margin-top: 3px; color: #fff;\">\u00a0<\/p><\/li><\/ul><\/p>\r\n                       \r\n\r\n\r\n                  <\/div>\r\n                    <div class=\"col-md-8 text-right\">\r\n                        <div class=\"zoom-img--main text-right\">\r\n                          <img decoding=\"async\" class=\"mt-addons-tab-content-image\" src=\"https:\/\/drivendivinevilla.com\/wp-content\/uploads\/2024\/02\/IMG_7885.jpg\" alt=\"tabs-image\">\r\n                        <\/div>\r\n                  <\/div>\r\n                <\/div>   \r\n              <\/div>   \r\n            <\/section>\r\n                                  <section id=\"section-iconbox-3\">\r\n              <div class=\"row\">\r\n                <div class=\"mt-addons-tab-flex-zone\">\r\n                  <div class=\"col-md-4 col-sm-12 text-left\">\r\n                      <p class=\"mt-addons-tab-content-title\">Generously sized living spaces, an expansive master bedroom retreat, open-concept design for versatility, and effortlessly elegant bathrooms define the room dimensions of this captivating space.<\/p>\r\n                      <p class=\"mt-addons-tab-content\"><ul class=\"skyhaus-zone-flex\" style=\"padding-left: 0rem; padding-top: 40px;\"><li style=\"list-style: none; color: #c4c4c4;\">Generously Living Spaces<br \/><p class=\"skyhaus-description\" style=\"margin-top: 3px; color: #fff;\">\u00a0<\/p><\/li><li style=\"list-style: none; color: #c4c4c4;\"><p class=\"skyhaus-description\" style=\"margin-top: 3px; color: #fff;\"><span style=\"color: #c4c4c4;\">Open-Concept Design<\/span><\/p><\/li><\/ul><ul class=\"skyhaus-zone-flex-2\" style=\"padding-left: 0rem;\"><li style=\"list-style: none;\"><br \/><p class=\"skyhaus-description\" style=\"margin-top: 3px; color: #fff;\">\u00a0<\/p><\/li><\/ul><\/p>\r\n                       \r\n\r\n\r\n                  <\/div>\r\n                    <div class=\"col-md-8 text-right\">\r\n                        <div class=\"zoom-img--main text-right\">\r\n                          <img decoding=\"async\" class=\"mt-addons-tab-content-image\" src=\"https:\/\/drivendivinevilla.com\/wp-content\/uploads\/2024\/02\/IMG_1141.jpg\" alt=\"tabs-image\">\r\n                        <\/div>\r\n                  <\/div>\r\n                <\/div>   \r\n              <\/div>   \r\n            <\/section>\r\n                                    <\/div>\r\n    <\/div>\r\n    \t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-0ce6121 elementor-widget elementor-widget-mt-spacer\" data-id=\"0ce6121\" data-element_type=\"widget\" data-widget_type=\"mt-spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t    <div class=\"mt-addons-flexible-spacer \">\r\n      <div class=\"mt-addons-empty-spacer-desktop\" style=\"height: 70px;\"><\/div>\r\n      <div class=\"mt-addons-empty-spacer-mobile\" style=\"height: 50px;\"><\/div>\r\n      <div class=\"mt-addons-empty-spacer-tablet\" style=\"height: 70px;\"><\/div>\r\n    <\/div>\r\n   \r\n    \t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-ef3d522 elementor-section-stretched elementor-section-boxed elementor-section-height-default elementor-section-height-default elementor-invisible\" data-id=\"ef3d522\" data-element_type=\"section\" data-settings=\"{&quot;stretch_section&quot;:&quot;section-stretched&quot;,&quot;animation&quot;:&quot;fadeIn&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-9088833\" data-id=\"9088833\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-a920b2d elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"a920b2d\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-20 elementor-inner-column elementor-element elementor-element-8d999c4\" data-id=\"8d999c4\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-ad1ea8a elementor-widget elementor-widget-icon-with-text\" data-id=\"ad1ea8a\" data-element_type=\"widget\" data-widget_type=\"icon-with-text.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t  <div style=\";;\" class=\"mt-icon-listgroup-item wow   text-center \">\r\n      <div class=\"mt-icon-listgroup-holder mt-addons-top_content\" >\r\n\r\n        <div class=\"mt-icon-listgroup-icon-holder-inner \" >\r\n                    <a href=\"\" target=\"_blank\" rel=\"\">\r\n            <img decoding=\"async\" alt=\"list-image\" style=\"max-width:60px;margin-right: px;\" class=\"mt-image-list\" src=\"https:\/\/drivendivinevilla.com\/wp-content\/uploads\/2024\/02\/IMG_1184.jpg\">\r\n          <\/a>\r\n                  <\/div>\r\n        <div class=\"mt-icon-listgroup-content-holder-inner\" >\r\n          <h6 class=\"mt-icon-listgroup-title\"><a href=\"\" target=\"_blank\" rel=\"\" style=\"\">Mega Mart<\/a>\r\n          <\/h6>\r\n                      <p class=\"mt-icon-listgroup-text\" style=\"\"> 13 Minutes <\/p>      \r\n                   <\/div>\r\n      <\/div>\r\n   <\/div>\r\n     \t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-20 elementor-inner-column elementor-element elementor-element-d18120d\" data-id=\"d18120d\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-233371d elementor-widget elementor-widget-icon-with-text\" data-id=\"233371d\" data-element_type=\"widget\" data-widget_type=\"icon-with-text.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t  <div style=\";;\" class=\"mt-icon-listgroup-item wow   text-center \">\r\n      <div class=\"mt-icon-listgroup-holder mt-addons-top_content\" >\r\n\r\n        <div class=\"mt-icon-listgroup-icon-holder-inner \" >\r\n                    <a href=\"\" target=\"_blank\" rel=\"\">\r\n            <img decoding=\"async\" alt=\"list-image\" style=\"max-width:60px;margin-right: px;\" class=\"mt-image-list\" src=\"https:\/\/drivendivinevilla.com\/wp-content\/uploads\/2024\/02\/IMG_1185.jpg\">\r\n          <\/a>\r\n                  <\/div>\r\n        <div class=\"mt-icon-listgroup-content-holder-inner\" >\r\n          <h6 class=\"mt-icon-listgroup-title\"><a href=\"\" target=\"_blank\" rel=\"\" style=\"\">Downtown<\/a>\r\n          <\/h6>\r\n                      <p class=\"mt-icon-listgroup-text\" style=\"\"> 12 Minutes <\/p>      \r\n                   <\/div>\r\n      <\/div>\r\n   <\/div>\r\n     \t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-20 elementor-inner-column elementor-element elementor-element-a582c9b\" data-id=\"a582c9b\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-8380ef8 elementor-widget elementor-widget-icon-with-text\" data-id=\"8380ef8\" data-element_type=\"widget\" data-widget_type=\"icon-with-text.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t  <div style=\";;\" class=\"mt-icon-listgroup-item wow   text-center \">\r\n      <div class=\"mt-icon-listgroup-holder mt-addons-top_content\" >\r\n\r\n        <div class=\"mt-icon-listgroup-icon-holder-inner \" >\r\n                    <a href=\"\" target=\"_blank\" rel=\"\">\r\n            <img decoding=\"async\" alt=\"list-image\" style=\"max-width:60px;margin-right: px;\" class=\"mt-image-list\" src=\"https:\/\/drivendivinevilla.com\/wp-content\/uploads\/2024\/02\/IMG_1186.jpg\">\r\n          <\/a>\r\n                  <\/div>\r\n        <div class=\"mt-icon-listgroup-content-holder-inner\" >\r\n          <h6 class=\"mt-icon-listgroup-title\"><a href=\"\" target=\"_blank\" rel=\"\" style=\"\">Bus &amp; Taxi<\/a>\r\n          <\/h6>\r\n                      <p class=\"mt-icon-listgroup-text\" style=\"\"> 14 Minutes <\/p>      \r\n                   <\/div>\r\n      <\/div>\r\n   <\/div>\r\n     \t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-20 elementor-inner-column elementor-element elementor-element-58721ea\" data-id=\"58721ea\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-b9529fd elementor-widget elementor-widget-icon-with-text\" data-id=\"b9529fd\" data-element_type=\"widget\" data-widget_type=\"icon-with-text.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t  <div style=\";;\" class=\"mt-icon-listgroup-item wow   text-center \">\r\n      <div class=\"mt-icon-listgroup-holder mt-addons-top_content\" >\r\n\r\n        <div class=\"mt-icon-listgroup-icon-holder-inner \" >\r\n                    <a href=\"\" target=\"_blank\" rel=\"\">\r\n            <img decoding=\"async\" alt=\"list-image\" style=\"max-width:60px;margin-right: px;\" class=\"mt-image-list\" src=\"https:\/\/drivendivinevilla.com\/wp-content\/uploads\/2024\/02\/IMG_1187.jpg\">\r\n          <\/a>\r\n                  <\/div>\r\n        <div class=\"mt-icon-listgroup-content-holder-inner\" >\r\n          <h6 class=\"mt-icon-listgroup-title\"><a href=\"\" target=\"_blank\" rel=\"\" style=\"\">Mandeville Hospital<\/a>\r\n          <\/h6>\r\n                      <p class=\"mt-icon-listgroup-text\" style=\"\"> 12 Minutes <\/p>      \r\n                   <\/div>\r\n      <\/div>\r\n   <\/div>\r\n     \t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-20 elementor-inner-column elementor-element elementor-element-29c2313\" data-id=\"29c2313\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-eb0742a elementor-widget elementor-widget-icon-with-text\" data-id=\"eb0742a\" data-element_type=\"widget\" data-widget_type=\"icon-with-text.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t  <div style=\";;\" class=\"mt-icon-listgroup-item wow   text-center \">\r\n      <div class=\"mt-icon-listgroup-holder mt-addons-top_content\" >\r\n\r\n        <div class=\"mt-icon-listgroup-icon-holder-inner \" >\r\n                    <a href=\"\" target=\"_blank\" rel=\"\">\r\n            <img decoding=\"async\" alt=\"list-image\" style=\"max-width:60px;margin-right: px;\" class=\"mt-image-list\" src=\"https:\/\/drivendivinevilla.com\/wp-content\/uploads\/2024\/02\/IMG_1188.jpg\">\r\n          <\/a>\r\n                  <\/div>\r\n        <div class=\"mt-icon-listgroup-content-holder-inner\" >\r\n          <h6 class=\"mt-icon-listgroup-title\"><a href=\"\" target=\"_blank\" rel=\"\" style=\"\">Northern Caribbean University<\/a>\r\n          <\/h6>\r\n                      <p class=\"mt-icon-listgroup-text\" style=\"\"> 8 Minutes <\/p>      \r\n                   <\/div>\r\n      <\/div>\r\n   <\/div>\r\n     \t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-ac4ec32 elementor-section-boxed elementor-section-height-default elementor-section-height-default elementor-invisible\" data-id=\"ac4ec32\" data-element_type=\"section\" id=\"rooms\" data-settings=\"{&quot;animation&quot;:&quot;fadeInUp&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-c477559\" data-id=\"c477559\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-ab139dd elementor-widget elementor-widget-mt-spacer\" data-id=\"ab139dd\" data-element_type=\"widget\" data-widget_type=\"mt-spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t    <div class=\"mt-addons-flexible-spacer \">\r\n      <div class=\"mt-addons-empty-spacer-desktop\" style=\"height: 21px;\"><\/div>\r\n      <div class=\"mt-addons-empty-spacer-mobile\" style=\"height: 21px;\"><\/div>\r\n      <div class=\"mt-addons-empty-spacer-tablet\" style=\"height: 21px;\"><\/div>\r\n    <\/div>\r\n   \r\n    \t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-bee3388 tabs-strong elementor-widget elementor-widget-mt-tabs-style-v2\" data-id=\"bee3388\" data-element_type=\"widget\" data-widget_type=\"mt-tabs-style-v2.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t            <div class=\"mt-addons-tabs-v2\">\r\n                <nav>\r\n                    <div class=\"mt-addons-header-tabs col-md-12\">\r\n                        <h5 class=\"mt-addons-tabs-nav-title-header-top col-md-6\"><\/h5>\r\n\r\n                        <h2 class=\"mt-addons-tabs-nav-title-top col-md-6\">DRIVEN &amp; DIVINE DELIGHTS<\/h2>\r\n                    <\/div>\r\n                    <ul class=\"mt-addons-tabs-nav-v2 col-md-6\" style=\"background:\"> \r\n                                                                              \r\n\r\n                              <li><a href=\"#section-iconbox-v2-1\"> \r\n                                <h5 class=\"mt-addons-tabs-nav-title\" style=\"color:;\">Enchanting Garden Haven<\/h5>\r\n                              <\/a><\/li> \r\n                                                            \r\n\r\n                              <li><a href=\"#section-iconbox-v2-2\"> \r\n                                <h5 class=\"mt-addons-tabs-nav-title\" style=\"color:;\">Main Bar Escape<\/h5>\r\n                              <\/a><\/li> \r\n                                                            \r\n\r\n                              <li><a href=\"#section-iconbox-v2-3\"> \r\n                                <h5 class=\"mt-addons-tabs-nav-title\" style=\"color:;\">Epic Kitchen Hub<\/h5>\r\n                              <\/a><\/li> \r\n                                                                                                      <\/ul>\r\n                <\/nav>\r\n                <div class=\"mt-addons-tab-content-v2\">\r\n                                                                                        <section id=\"section-iconbox-v2-1\">\r\n                            <div class=\"row\">\r\n                                <div class=\"col-md-6 text-left\"> \r\n                                    <img decoding=\"async\" class=\"mt-addons-tab-content-image\" src=\"http:\/\/drivendivinevilla.com\/wp-content\/uploads\/2024\/02\/IMG_1201-scaled.jpg\" alt=\"tabs-image\">\r\n                                <\/div>\r\n                                <div class=\"mt-addons-tab-v2-description col-md-6 text-left\">\r\n                                    <p class=\"mt-addons-tab-content-title\"><\/p>\r\n                                    <!-- <div class=\"mt-addons-tab-content-v2\"><\/div> -->\r\n                                    <div class=\"mt-addons-tab-content-v2\"><p>The enchanting garden surrounding\u00a0 is a vibrant tapestry of colors, with meticulously arranged flowers creating a captivating display, while lush greenery and strategically placed pathways invite leisurely strolls in this botanical paradise.<\/p><\/div>\r\n                                                                     <\/div>\r\n                          <\/div>                     \r\n                        <\/section>\r\n                                                                      <section id=\"section-iconbox-v2-2\">\r\n                            <div class=\"row\">\r\n                                <div class=\"col-md-6 text-left\"> \r\n                                    <img decoding=\"async\" class=\"mt-addons-tab-content-image\" src=\"http:\/\/drivendivinevilla.com\/wp-content\/uploads\/2024\/02\/IMG_1199-scaled.jpg\" alt=\"tabs-image\">\r\n                                <\/div>\r\n                                <div class=\"mt-addons-tab-v2-description col-md-6 text-left\">\r\n                                    <p class=\"mt-addons-tab-content-title\"><\/p>\r\n                                    <!-- <div class=\"mt-addons-tab-content-v2\"><\/div> -->\r\n                                    <div class=\"mt-addons-tab-content-v2\"><p>Full-size bar radiates sophistication, featuring rich hardwood accents, a gleaming counter, and ambient lighting, creating an inviting space for events, socializing, and relaxation.<\/p><\/div>\r\n                                                                     <\/div>\r\n                          <\/div>                     \r\n                        <\/section>\r\n                                                                      <section id=\"section-iconbox-v2-3\">\r\n                            <div class=\"row\">\r\n                                <div class=\"col-md-6 text-left\"> \r\n                                    <img decoding=\"async\" class=\"mt-addons-tab-content-image\" src=\"http:\/\/drivendivinevilla.com\/wp-content\/uploads\/2024\/02\/IMG_1200-scaled.jpg\" alt=\"tabs-image\">\r\n                                <\/div>\r\n                                <div class=\"mt-addons-tab-v2-description col-md-6 text-left\">\r\n                                    <p class=\"mt-addons-tab-content-title\"><\/p>\r\n                                    <!-- <div class=\"mt-addons-tab-content-v2\"><\/div> -->\r\n                                    <div class=\"mt-addons-tab-content-v2\"><p>Full commercial kitchen designed for grand events, equipped with state-of-the-art appliances, expansive countertops, and a seamlessly integrated dining area, creating a culinary haven for memorable gatherings.<\/p><\/div>\r\n                                                                     <\/div>\r\n                          <\/div>                     \r\n                        <\/section>\r\n                                                                                  <\/div>\r\n            <\/div>\r\n    \t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5a61be7 elementor-widget elementor-widget-mt-spacer\" data-id=\"5a61be7\" data-element_type=\"widget\" data-widget_type=\"mt-spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t    <div class=\"mt-addons-flexible-spacer \">\r\n      <div class=\"mt-addons-empty-spacer-desktop\" style=\"height: 42px;\"><\/div>\r\n      <div class=\"mt-addons-empty-spacer-mobile\" style=\"height: 42px;\"><\/div>\r\n      <div class=\"mt-addons-empty-spacer-tablet\" style=\"height: 42px;\"><\/div>\r\n    <\/div>\r\n   \r\n    \t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t<div class=\"elementor-element elementor-element-a60dc92 e-flex e-con-boxed e-con e-parent\" data-id=\"a60dc92\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-2fcd063 elementor-widget elementor-widget-video\" data-id=\"2fcd063\" data-element_type=\"widget\" data-settings=\"{&quot;youtube_url&quot;:&quot;https:\\\/\\\/youtu.be\\\/7oYLhKhHXcU?si=dRYinW4W7Hq1V33c&quot;,&quot;video_type&quot;:&quot;youtube&quot;,&quot;controls&quot;:&quot;yes&quot;}\" data-widget_type=\"video.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-wrapper elementor-open-inline\">\n\t\t\t<div class=\"elementor-video\"><\/div>\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-f92a040 e-flex e-con-boxed e-con e-parent\" data-id=\"f92a040\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-4d6f9df elementor-widget elementor-widget-spacer\" data-id=\"4d6f9df\" data-element_type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-193f1c6 elementor-section-stretched elementor-section-boxed elementor-section-height-default elementor-section-height-default elementor-invisible\" data-id=\"193f1c6\" data-element_type=\"section\" id=\"gallery\" data-settings=\"{&quot;stretch_section&quot;:&quot;section-stretched&quot;,&quot;background_background&quot;:&quot;classic&quot;,&quot;animation&quot;:&quot;fadeInUp&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-0ae58fe\" data-id=\"0ae58fe\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-0bd65e8 elementor-widget elementor-widget-mt-spacer\" data-id=\"0bd65e8\" data-element_type=\"widget\" data-widget_type=\"mt-spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t    <div class=\"mt-addons-flexible-spacer \">\r\n      <div class=\"mt-addons-empty-spacer-desktop\" style=\"height: 60px;\"><\/div>\r\n      <div class=\"mt-addons-empty-spacer-mobile\" style=\"height: 50px;\"><\/div>\r\n      <div class=\"mt-addons-empty-spacer-tablet\" style=\"height: 40px;\"><\/div>\r\n    <\/div>\r\n   \r\n    \t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-83c3dce elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"83c3dce\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-3fac3e4 tablet-view2\" data-id=\"3fac3e4\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-345919c elementor-widget elementor-widget-title-subtitle\" data-id=\"345919c\" data-element_type=\"widget\" data-widget_type=\"title-subtitle.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t    <div  class=\"mt-addons-title-subtile \">\r\n      \r\n      \r\n      \r\n                           \r\n      <h2 class=\"mt-addons-title-section text-left\" style=\"color:#0A0A0A;font-weight:;font-size:px;\">EXPLORE SOME OF THE AMAZING EVENTS YOU CAN HOST AT DRIVEN &amp; DIVINE <span class=\"mt-underline-text curved\" style=\"color:#0A0A0A;\"><\/span> <\/h2>\r\n\r\n                    \r\n          <\/div>\r\n\r\n    \t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-65405cc\" data-id=\"65405cc\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-da04524 row-class elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"da04524\" data-element_type=\"section\" data-settings=\"{&quot;animation&quot;:&quot;none&quot;,&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-25d6860\" data-id=\"25d6860\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-f895fc5 elementor-widget elementor-widget-mt-fancy-gallery-tabs\" data-id=\"f895fc5\" data-element_type=\"widget\" data-widget_type=\"mt-fancy-gallery-tabs.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t            <div class=\"mt-addons-fancy-gallery-tabs tab-container\">\r\n                <nav>\r\n                    <ul class=\"mt-addons-fancy-gallery col-md-2\" style=\"background:\"> \r\n                                                                              \r\n                              <li><a href=\"#section-fancy-iconbox-1\"> \r\n                                <h5 class=\"mt-addons-mt-addons-fancy-gallery-tabs-nav-title\" style=\"color:#C4C4C4;\">WEDDING &amp; RECEPTION<\/h5>\r\n                              <\/a><\/li> \r\n                                                            \r\n                              <li><a href=\"#section-fancy-iconbox-2\"> \r\n                                <h5 class=\"mt-addons-mt-addons-fancy-gallery-tabs-nav-title\" style=\"color:#C4C4C4;\">CORPORATE EVENT<\/h5>\r\n                              <\/a><\/li> \r\n                                                            \r\n                              <li><a href=\"#section-fancy-iconbox-3\"> \r\n                                <h5 class=\"mt-addons-mt-addons-fancy-gallery-tabs-nav-title\" style=\"color:#C4C4C4;\">GRADUATION PARTY<\/h5>\r\n                              <\/a><\/li> \r\n                                                            \r\n                              <li><a href=\"#section-fancy-iconbox-4\"> \r\n                                <h5 class=\"mt-addons-mt-addons-fancy-gallery-tabs-nav-title\" style=\"color:#C4C4C4;\">BABY SHOWER<\/h5>\r\n                              <\/a><\/li> \r\n                                                            \r\n                              <li><a href=\"#section-fancy-iconbox-5\"> \r\n                                <h5 class=\"mt-addons-mt-addons-fancy-gallery-tabs-nav-title\" style=\"color:#C4C4C4;\">FAMILY REUNION<\/h5>\r\n                              <\/a><\/li> \r\n                                                            \r\n                              <li><a href=\"#section-fancy-iconbox-6\"> \r\n                                <h5 class=\"mt-addons-mt-addons-fancy-gallery-tabs-nav-title\" style=\"color:#C4C4C4;\">VIDEO\/PHOTO SHOOT<\/h5>\r\n                              <\/a><\/li> \r\n                                                                                                      <\/ul>\r\n                <\/nav>\r\n                <div class=\"mt-addons-tab-fancy-gallery-content\">\r\n                                                                                        <section id=\"section-fancy-iconbox-1\">\r\n                            <div class=\"row\">\r\n                                <div class=\"mt-addons-tab-fancy-gallery-flex-zone\">\r\n                                    <div class=\"mt-addons-tab-fancy-gallery-description col-lg-4 text-left\">\r\n                                        <p class=\"mt-addons-tab-fancy-gallery-title\"><\/p>\r\n                                        <div class=\"mt-addons-tab-fancy-gallery-content\"><p>We curate unforgettable weddings and receptions, capturing every cherished moment with grace and style.<\/p><\/div>\r\n                                                                             <\/div>\r\n                                    <div class=\"col-lg-9\"> \r\n                                        <div class=\"mt-addons-tab-fancy-gallery-wrapper clearfix\">\r\n                                            <div class=\"col-lg-6 icons mt-addons-tab-fancy-gallery-grid-item-1\">\r\n                                              <img decoding=\"async\" class=\"mt-addons-tab-fancy-gallery-image\" src=\"http:\/\/drivendivinevilla.com\/wp-content\/uploads\/2024\/02\/IMG_1149-scaled.jpg\" alt=\"fancy-gallery-tabs-image\">\r\n                                            <\/div>\r\n                                            <div class=\"col-lg-6 icons mt-addons-tab-fancy-gallery-grid-ite-2\">\r\n                                              <img decoding=\"async\" class=\"mt-addons-tab-fancy-gallery-image\" src=\"http:\/\/drivendivinevilla.com\/wp-content\/uploads\/2024\/02\/IMG_1150-scaled-e1727046347213.jpg\" alt=\"fancy-gallery-tabs-image\">\r\n                                            <\/div>\r\n                                            <div class=\"col-lg-6 icons mt-addons-tab-fancy-gallery-grid-item-3\">\r\n                                              <img decoding=\"async\" class=\"mt-addons-tab-fancy-gallery-image\" src=\"http:\/\/drivendivinevilla.com\/wp-content\/uploads\/2024\/02\/IMG_1152-scaled.jpg\" alt=\"fancy-gallery-tabs-image\">\r\n                                            <\/div>\r\n                                            <div class=\"col-lg-6 icons mt-addons-tab-fancy-gallery-grid-item-4\">\r\n                                              <img decoding=\"async\" class=\"mt-addons-tab-fancy-gallery-image\" src=\"\" alt=\"fancy-gallery-tabs-image\">\r\n                                            <\/div>\r\n                                        <\/div>\r\n                                    <\/div>\r\n                              <\/div>  \r\n                          <\/div>  \r\n                        <\/section>\r\n                                                                      <section id=\"section-fancy-iconbox-2\">\r\n                            <div class=\"row\">\r\n                                <div class=\"mt-addons-tab-fancy-gallery-flex-zone\">\r\n                                    <div class=\"mt-addons-tab-fancy-gallery-description col-lg-4 text-left\">\r\n                                        <p class=\"mt-addons-tab-fancy-gallery-title\"><\/p>\r\n                                        <div class=\"mt-addons-tab-fancy-gallery-content\"><p>The full landscape for you to host your corporate events, where professionalism meets sophistication.<\/p><\/div>\r\n                                                                             <\/div>\r\n                                    <div class=\"col-lg-9\"> \r\n                                        <div class=\"mt-addons-tab-fancy-gallery-wrapper clearfix\">\r\n                                            <div class=\"col-lg-6 icons mt-addons-tab-fancy-gallery-grid-item-1\">\r\n                                              <img decoding=\"async\" class=\"mt-addons-tab-fancy-gallery-image\" src=\"http:\/\/drivendivinevilla.com\/wp-content\/uploads\/2024\/02\/IMG_1170-scaled.jpg\" alt=\"fancy-gallery-tabs-image\">\r\n                                            <\/div>\r\n                                            <div class=\"col-lg-6 icons mt-addons-tab-fancy-gallery-grid-ite-2\">\r\n                                              <img decoding=\"async\" class=\"mt-addons-tab-fancy-gallery-image\" src=\"http:\/\/drivendivinevilla.com\/wp-content\/uploads\/2024\/02\/IMG_1169-scaled.jpg\" alt=\"fancy-gallery-tabs-image\">\r\n                                            <\/div>\r\n                                            <div class=\"col-lg-6 icons mt-addons-tab-fancy-gallery-grid-item-3\">\r\n                                              <img decoding=\"async\" class=\"mt-addons-tab-fancy-gallery-image\" src=\"http:\/\/drivendivinevilla.com\/wp-content\/uploads\/2024\/02\/IMG_1168-scaled.jpg\" alt=\"fancy-gallery-tabs-image\">\r\n                                            <\/div>\r\n                                            <div class=\"col-lg-6 icons mt-addons-tab-fancy-gallery-grid-item-4\">\r\n                                              <img decoding=\"async\" class=\"mt-addons-tab-fancy-gallery-image\" src=\"http:\/\/drivendivinevilla.com\/wp-content\/uploads\/2024\/02\/IMG_1171-scaled.jpg\" alt=\"fancy-gallery-tabs-image\">\r\n                                            <\/div>\r\n                                        <\/div>\r\n                                    <\/div>\r\n                              <\/div>  \r\n                          <\/div>  \r\n                        <\/section>\r\n                                                                      <section id=\"section-fancy-iconbox-3\">\r\n                            <div class=\"row\">\r\n                                <div class=\"mt-addons-tab-fancy-gallery-flex-zone\">\r\n                                    <div class=\"mt-addons-tab-fancy-gallery-description col-lg-4 text-left\">\r\n                                        <p class=\"mt-addons-tab-fancy-gallery-title\"><\/p>\r\n                                        <div class=\"mt-addons-tab-fancy-gallery-content\"><p>Celebrate milestones in style with our tailored spaces, creating memorable graduation parties.<\/p><\/div>\r\n                                                                             <\/div>\r\n                                    <div class=\"col-lg-9\"> \r\n                                        <div class=\"mt-addons-tab-fancy-gallery-wrapper clearfix\">\r\n                                            <div class=\"col-lg-6 icons mt-addons-tab-fancy-gallery-grid-item-1\">\r\n                                              <img decoding=\"async\" class=\"mt-addons-tab-fancy-gallery-image\" src=\"http:\/\/drivendivinevilla.com\/wp-content\/uploads\/2024\/02\/IMG_0518.jpg\" alt=\"fancy-gallery-tabs-image\">\r\n                                            <\/div>\r\n                                            <div class=\"col-lg-6 icons mt-addons-tab-fancy-gallery-grid-ite-2\">\r\n                                              <img decoding=\"async\" class=\"mt-addons-tab-fancy-gallery-image\" src=\"http:\/\/drivendivinevilla.com\/wp-content\/uploads\/2024\/02\/IMG_0517-1.jpg\" alt=\"fancy-gallery-tabs-image\">\r\n                                            <\/div>\r\n                                            <div class=\"col-lg-6 icons mt-addons-tab-fancy-gallery-grid-item-3\">\r\n                                              <img decoding=\"async\" class=\"mt-addons-tab-fancy-gallery-image\" src=\"http:\/\/drivendivinevilla.com\/wp-content\/uploads\/2024\/02\/IMG_0519-e1727046540902.png\" alt=\"fancy-gallery-tabs-image\">\r\n                                            <\/div>\r\n                                            <div class=\"col-lg-6 icons mt-addons-tab-fancy-gallery-grid-item-4\">\r\n                                              <img decoding=\"async\" class=\"mt-addons-tab-fancy-gallery-image\" src=\"http:\/\/drivendivinevilla.com\/wp-content\/uploads\/2024\/02\/IMG_0520.png\" alt=\"fancy-gallery-tabs-image\">\r\n                                            <\/div>\r\n                                        <\/div>\r\n                                    <\/div>\r\n                              <\/div>  \r\n                          <\/div>  \r\n                        <\/section>\r\n                                                                      <section id=\"section-fancy-iconbox-4\">\r\n                            <div class=\"row\">\r\n                                <div class=\"mt-addons-tab-fancy-gallery-flex-zone\">\r\n                                    <div class=\"mt-addons-tab-fancy-gallery-description col-lg-4 text-left\">\r\n                                        <p class=\"mt-addons-tab-fancy-gallery-title\"><\/p>\r\n                                        <div class=\"mt-addons-tab-fancy-gallery-content\"><p>Cherish the arrival of new beginnings with heartwarming baby showers held at the villa entire landscape<\/p><\/div>\r\n                                                                             <\/div>\r\n                                    <div class=\"col-lg-9\"> \r\n                                        <div class=\"mt-addons-tab-fancy-gallery-wrapper clearfix\">\r\n                                            <div class=\"col-lg-6 icons mt-addons-tab-fancy-gallery-grid-item-1\">\r\n                                              <img decoding=\"async\" class=\"mt-addons-tab-fancy-gallery-image\" src=\"http:\/\/drivendivinevilla.com\/wp-content\/uploads\/2024\/02\/IMG_0486-scaled.jpg\" alt=\"fancy-gallery-tabs-image\">\r\n                                            <\/div>\r\n                                            <div class=\"col-lg-6 icons mt-addons-tab-fancy-gallery-grid-ite-2\">\r\n                                              <img decoding=\"async\" class=\"mt-addons-tab-fancy-gallery-image\" src=\"http:\/\/drivendivinevilla.com\/wp-content\/uploads\/2024\/02\/IMG_0483-scaled.jpg\" alt=\"fancy-gallery-tabs-image\">\r\n                                            <\/div>\r\n                                            <div class=\"col-lg-6 icons mt-addons-tab-fancy-gallery-grid-item-3\">\r\n                                              <img decoding=\"async\" class=\"mt-addons-tab-fancy-gallery-image\" src=\"http:\/\/drivendivinevilla.com\/wp-content\/uploads\/2024\/02\/IMG_0485-1-scaled.jpg\" alt=\"fancy-gallery-tabs-image\">\r\n                                            <\/div>\r\n                                            <div class=\"col-lg-6 icons mt-addons-tab-fancy-gallery-grid-item-4\">\r\n                                              <img decoding=\"async\" class=\"mt-addons-tab-fancy-gallery-image\" src=\"http:\/\/drivendivinevilla.com\/wp-content\/uploads\/2024\/02\/IMG_0487-scaled.jpg\" alt=\"fancy-gallery-tabs-image\">\r\n                                            <\/div>\r\n                                        <\/div>\r\n                                    <\/div>\r\n                              <\/div>  \r\n                          <\/div>  \r\n                        <\/section>\r\n                                                                      <section id=\"section-fancy-iconbox-5\">\r\n                            <div class=\"row\">\r\n                                <div class=\"mt-addons-tab-fancy-gallery-flex-zone\">\r\n                                    <div class=\"mt-addons-tab-fancy-gallery-description col-lg-4 text-left\">\r\n                                        <p class=\"mt-addons-tab-fancy-gallery-title\"><\/p>\r\n                                        <div class=\"mt-addons-tab-fancy-gallery-content\"><p>At our villa, savor the moments of togetherness during your family reunion, where every corner echoes with warmth and shared memories.<\/p><\/div>\r\n                                                                             <\/div>\r\n                                    <div class=\"col-lg-9\"> \r\n                                        <div class=\"mt-addons-tab-fancy-gallery-wrapper clearfix\">\r\n                                            <div class=\"col-lg-6 icons mt-addons-tab-fancy-gallery-grid-item-1\">\r\n                                              <img decoding=\"async\" class=\"mt-addons-tab-fancy-gallery-image\" src=\"http:\/\/drivendivinevilla.com\/wp-content\/uploads\/2024\/02\/IMG_0513.jpg\" alt=\"fancy-gallery-tabs-image\">\r\n                                            <\/div>\r\n                                            <div class=\"col-lg-6 icons mt-addons-tab-fancy-gallery-grid-ite-2\">\r\n                                              <img decoding=\"async\" class=\"mt-addons-tab-fancy-gallery-image\" src=\"http:\/\/drivendivinevilla.com\/wp-content\/uploads\/2024\/02\/IMG_0515.jpg\" alt=\"fancy-gallery-tabs-image\">\r\n                                            <\/div>\r\n                                            <div class=\"col-lg-6 icons mt-addons-tab-fancy-gallery-grid-item-3\">\r\n                                              <img decoding=\"async\" class=\"mt-addons-tab-fancy-gallery-image\" src=\"http:\/\/drivendivinevilla.com\/wp-content\/uploads\/2024\/02\/IMG_0514.jpg\" alt=\"fancy-gallery-tabs-image\">\r\n                                            <\/div>\r\n                                            <div class=\"col-lg-6 icons mt-addons-tab-fancy-gallery-grid-item-4\">\r\n                                              <img decoding=\"async\" class=\"mt-addons-tab-fancy-gallery-image\" src=\"http:\/\/drivendivinevilla.com\/wp-content\/uploads\/2024\/02\/IMG_0516.jpg\" alt=\"fancy-gallery-tabs-image\">\r\n                                            <\/div>\r\n                                        <\/div>\r\n                                    <\/div>\r\n                              <\/div>  \r\n                          <\/div>  \r\n                        <\/section>\r\n                                                                      <section id=\"section-fancy-iconbox-6\">\r\n                            <div class=\"row\">\r\n                                <div class=\"mt-addons-tab-fancy-gallery-flex-zone\">\r\n                                    <div class=\"mt-addons-tab-fancy-gallery-description col-lg-4 text-left\">\r\n                                        <p class=\"mt-addons-tab-fancy-gallery-title\"><\/p>\r\n                                        <div class=\"mt-addons-tab-fancy-gallery-content\"><p>Elevate your visual storytelling with professional video and photo shoots at our villa \u2013 a canvas for capturing moments in all their brilliance.<\/p><\/div>\r\n                                                                             <\/div>\r\n                                    <div class=\"col-lg-9\"> \r\n                                        <div class=\"mt-addons-tab-fancy-gallery-wrapper clearfix\">\r\n                                            <div class=\"col-lg-6 icons mt-addons-tab-fancy-gallery-grid-item-1\">\r\n                                              <img decoding=\"async\" class=\"mt-addons-tab-fancy-gallery-image\" src=\"http:\/\/drivendivinevilla.com\/wp-content\/uploads\/2024\/02\/IMG_0521-scaled.jpg\" alt=\"fancy-gallery-tabs-image\">\r\n                                            <\/div>\r\n                                            <div class=\"col-lg-6 icons mt-addons-tab-fancy-gallery-grid-ite-2\">\r\n                                              <img decoding=\"async\" class=\"mt-addons-tab-fancy-gallery-image\" src=\"http:\/\/drivendivinevilla.com\/wp-content\/uploads\/2024\/02\/IMG_0522-scaled.jpg\" alt=\"fancy-gallery-tabs-image\">\r\n                                            <\/div>\r\n                                            <div class=\"col-lg-6 icons mt-addons-tab-fancy-gallery-grid-item-3\">\r\n                                              <img decoding=\"async\" class=\"mt-addons-tab-fancy-gallery-image\" src=\"http:\/\/drivendivinevilla.com\/wp-content\/uploads\/2024\/02\/IMG_0524-scaled.jpg\" alt=\"fancy-gallery-tabs-image\">\r\n                                            <\/div>\r\n                                            <div class=\"col-lg-6 icons mt-addons-tab-fancy-gallery-grid-item-4\">\r\n                                              <img decoding=\"async\" class=\"mt-addons-tab-fancy-gallery-image\" src=\"\" alt=\"fancy-gallery-tabs-image\">\r\n                                            <\/div>\r\n                                        <\/div>\r\n                                    <\/div>\r\n                              <\/div>  \r\n                          <\/div>  \r\n                        <\/section>\r\n                                                                                  <\/div>\r\n            <\/div>\r\n    \t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<div class=\"elementor-element elementor-element-40f2577 elementor-widget elementor-widget-mt-spacer\" data-id=\"40f2577\" data-element_type=\"widget\" data-widget_type=\"mt-spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t    <div class=\"mt-addons-flexible-spacer \">\r\n      <div class=\"mt-addons-empty-spacer-desktop\" style=\"height: 90px;\"><\/div>\r\n      <div class=\"mt-addons-empty-spacer-mobile\" style=\"height: 50px;\"><\/div>\r\n      <div class=\"mt-addons-empty-spacer-tablet\" style=\"height: 70px;\"><\/div>\r\n    <\/div>\r\n   \r\n    \t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t<div class=\"elementor-element elementor-element-e6b4caf e-flex e-con-boxed e-con e-parent\" data-id=\"e6b4caf\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-d34e352 elementor-widget elementor-widget-spacer\" data-id=\"d34e352\" data-element_type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-b595b13 e-flex e-con-boxed e-con e-parent\" data-id=\"b595b13\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-beafa0e elementor-widget elementor-widget-heading\" data-id=\"beafa0e\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">LOCATION<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-9502182 e-flex e-con-boxed e-con e-parent\" data-id=\"9502182\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-8cc6cd9 elementor-widget elementor-widget-google_maps\" data-id=\"8cc6cd9\" data-element_type=\"widget\" data-widget_type=\"google_maps.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-custom-embed\">\n\t\t\t<iframe loading=\"lazy\"\n\t\t\t\t\tsrc=\"https:\/\/maps.google.com\/maps?q=knockpartick%20mandveille%20jamaica&#038;t=m&#038;z=10&#038;output=embed&#038;iwloc=near\"\n\t\t\t\t\ttitle=\"knockpartick mandveille jamaica\"\n\t\t\t\t\taria-label=\"knockpartick mandveille jamaica\"\n\t\t\t><\/iframe>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-82409ee elementor-section-boxed elementor-section-height-default elementor-section-height-default elementor-invisible\" data-id=\"82409ee\" data-element_type=\"section\" id=\"team\" data-settings=\"{&quot;animation&quot;:&quot;fadeInUp&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-6b1cd8a\" data-id=\"6b1cd8a\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-95c02a5 elementor-widget elementor-widget-mt-spacer\" data-id=\"95c02a5\" data-element_type=\"widget\" data-widget_type=\"mt-spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t    <div class=\"mt-addons-flexible-spacer \">\r\n      <div class=\"mt-addons-empty-spacer-desktop\" style=\"height: 130px;\"><\/div>\r\n      <div class=\"mt-addons-empty-spacer-mobile\" style=\"height: 60px;\"><\/div>\r\n      <div class=\"mt-addons-empty-spacer-tablet\" style=\"height: 90px;\"><\/div>\r\n    <\/div>\r\n   \r\n    \t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-67b8827 team elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"67b8827\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-ca7bbcd\" data-id=\"ca7bbcd\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-8ae71a0 elementor-widget elementor-widget-title-subtitle\" data-id=\"8ae71a0\" data-element_type=\"widget\" data-widget_type=\"title-subtitle.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t    <div  class=\"mt-addons-title-subtile \">\r\n      \r\n      \r\n      \r\n                           \r\n      <h2 class=\"mt-addons-title-section text-left\" style=\"color:#0A0A0A;font-weight:;font-size:px;\">NEWS <span class=\"mt-underline-text curved\" style=\"color:#0A0A0A;\"><\/span> <\/h2>\r\n\r\n                    \r\n          <\/div>\r\n\r\n    \t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c63f984 skyhaus-members elementor-widget elementor-widget-mt-members\" data-id=\"c63f984\" data-element_type=\"widget\" data-widget_type=\"mt-members.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t              <div class=\"mt-swipper-carusel-position\" style=\"position:relative;\">\r\n      <div id=\"mt-addons-carousel-6a045ad82917e\" \r\n                  data-swiper-id=\"mt-addons-carousel-6a045ad82917e\"  \r\n        data-swiper-autoplay=\"\"\r\n        data-swiper-delay=\"600\" \r\n        data-swiper-desktop-items=\"2\" \r\n        data-swiper-mobile-items=\"1\" \r\n        data-swiper-tablet-items=\"2\" \r\n        data-swiper-space-between-items=\"30\" \r\n        data-swiper-allow-touch-move=\"yes\" \r\n        data-swiper-effect=\"\"\r\n        data-swiper-grab-cursor =\"\"\r\n        data-swiper-infinite-loop =\"\"\r\n        data-swiper-centered-slides =\"\"\r\n        data-swiper-navigation =\"\"\r\n        data-swiper-pagination =\"\"\r\n\r\n\r\n     \r\n        class=\"mt-addons-members mt-addons-swipper swiper\">\r\n\r\n                    <div class=\"swiper-wrapper\">\r\n                                                      \r\n                <div class=\"mt-addons-member-columns swiper-slide\">\r\n                  \r\n                                      <div class=\"mt-addons-member-image\">\r\n                      <img decoding=\"async\" src=\"https:\/\/drivendivinevilla.com\/wp-content\/uploads\/2024\/02\/1973D113-7DCE-4297-B3F2-0EBFD0096272-576x1024.png\" alt=\"BIG GIVEAWAY\" class=\"img-square\" \/>\r\n                      <div class=\"mt-addons-member-image-flex-zone icon-text img-square\" style=\"background:#02010100;\">\r\n                        <div class=\"mt-addons-member-image-flex-zone-inside member_social social-icons\">\r\n                                                                                                                                                                                                                                                                                                                                                                                                    <\/div>\r\n                      <\/div>\r\n                    <\/div>\r\n                                    <div class=\"mt-addons-member-section\"> \r\n                                          <h3 class=\"mt-addons-member-name\" style=\"font-size:px;\">\r\n                        <a href=\"\" class=\"mt-addons-member-url\" style=\"\">\r\n                          BIG GIVEAWAY                        <\/a>\r\n                      <\/h3>\r\n                                         \r\n                                          <div class=\"mt-addons-member-position\" style=\"\">COMING SOON<\/div>\r\n                    \r\n                                      <\/div>\r\n                <\/div>\r\n                          \r\n\r\n                    <\/div>\r\n                    \r\n        <i class=\"fas fa fa-arrow-left swiper-button-prev nav-square nav_above_right\" style=\"color:#010101;background:#FFFFFF\"><\/i>\r\n        <i class=\"fas fa fa-arrow-right swiper-button-next nav-square nav_above_right\" style=\"color:#010101;background:#FFFFFF\"><\/i>      <\/div>\r\n    <\/div>\r\n    <style type=\"text\/css\" media=\"screen\">\r\n      .swiper-button-prev:hover,\r\n      .swiper-button-next:hover {\r\n        background: #010101!important;\r\n        color: #FFFFFF!important;\r\n        opacity: 1;\r\n      }\r\n      .swiper-pagination-bullet {\r\n        background: !important;\r\n      }\r\n    <\/style>\r\n    \t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<div class=\"elementor-element elementor-element-f7a982e elementor-widget elementor-widget-mt-spacer\" data-id=\"f7a982e\" data-element_type=\"widget\" data-widget_type=\"mt-spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t    <div class=\"mt-addons-flexible-spacer \">\r\n      <div class=\"mt-addons-empty-spacer-desktop\" style=\"height: 70px;\"><\/div>\r\n      <div class=\"mt-addons-empty-spacer-mobile\" style=\"height: px;\"><\/div>\r\n      <div class=\"mt-addons-empty-spacer-tablet\" style=\"height: px;\"><\/div>\r\n    <\/div>\r\n   \r\n    \t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t<div class=\"elementor-element elementor-element-da2ab30 e-flex e-con-boxed e-con e-parent\" data-id=\"da2ab30\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Welcome toDriven &amp; Divine VILLA Send a inquiry Host your Next Event ! Send an inquiry DRIVEN &amp; DIVINE ENTERPRISE Experience the versatility of our villa, where the possibilities for events are endless! Whether you&#8217;re planning a corporate gathering, a cozy baby reveal, or a celebratory graduation party, our space caters to every occasion. With [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"inline_featured_image":false,"footnotes":""},"class_list":["post-1458","page","type-page","status-publish","hentry"],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/drivendivinevilla.com\/index.php\/wp-json\/wp\/v2\/pages\/1458","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/drivendivinevilla.com\/index.php\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/drivendivinevilla.com\/index.php\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/drivendivinevilla.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/drivendivinevilla.com\/index.php\/wp-json\/wp\/v2\/comments?post=1458"}],"version-history":[{"count":291,"href":"https:\/\/drivendivinevilla.com\/index.php\/wp-json\/wp\/v2\/pages\/1458\/revisions"}],"predecessor-version":[{"id":2972,"href":"https:\/\/drivendivinevilla.com\/index.php\/wp-json\/wp\/v2\/pages\/1458\/revisions\/2972"}],"wp:attachment":[{"href":"https:\/\/drivendivinevilla.com\/index.php\/wp-json\/wp\/v2\/media?parent=1458"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}